{"id":837,"count":1,"description":"","link":"https:\/\/www.juddbuilders.com\/juddbuildersblog\/tag\/townhouse\/","name":"Townhouse","slug":"townhouse","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.juddbuilders.com\/juddbuildersblog\/tag\/townhouse\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.juddbuilders.com\\\/juddbuildersblog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/837\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.juddbuilders.com\\\/juddbuildersblog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.juddbuilders.com\\\/juddbuildersblog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.juddbuilders.com\\\/juddbuildersblog\\\/tag\\\/townhouse\\\/#listItem\",\"name\":\"Townhouse\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.juddbuilders.com\\\/juddbuildersblog\\\/tag\\\/townhouse\\\/#listItem\",\"position\":2,\"name\":\"Townhouse\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.juddbuilders.com\\\/juddbuildersblog#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.juddbuilders.com\\\/juddbuildersblog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/837\\\/#collectionpage\",\"url\":\"https:\\\/\\\/www.juddbuilders.com\\\/juddbuildersblog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/837\\\/\",\"name\":\"Townhouse | Judd Builders\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.juddbuilders.com\\\/juddbuildersblog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.juddbuilders.com\\\/juddbuildersblog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/837\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.juddbuilders.com\\\/juddbuildersblog\\\/#organization\",\"name\":\"Judd Builders\",\"url\":\"https:\\\/\\\/www.juddbuilders.com\\\/juddbuildersblog\\\/\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.juddbuilders.com\\\/juddbuildersblog\\\/#website\",\"url\":\"https:\\\/\\\/www.juddbuilders.com\\\/juddbuildersblog\\\/\",\"name\":\"Judd Builders\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.juddbuilders.com\\\/juddbuildersblog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Townhouse | Judd Builders","description":"","canonical_url":"https:\/\/www.juddbuilders.com\/juddbuildersblog\/tag\/townhouse\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.juddbuilders.com\/juddbuildersblog\/wp-json\/wp\/v2\/tags\/837\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.juddbuilders.com\/juddbuildersblog#listItem","position":1,"name":"Home","item":"https:\/\/www.juddbuilders.com\/juddbuildersblog","nextItem":{"@type":"ListItem","@id":"https:\/\/www.juddbuilders.com\/juddbuildersblog\/tag\/townhouse\/#listItem","name":"Townhouse"}},{"@type":"ListItem","@id":"https:\/\/www.juddbuilders.com\/juddbuildersblog\/tag\/townhouse\/#listItem","position":2,"name":"Townhouse","previousItem":{"@type":"ListItem","@id":"https:\/\/www.juddbuilders.com\/juddbuildersblog#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/www.juddbuilders.com\/juddbuildersblog\/wp-json\/wp\/v2\/tags\/837\/#collectionpage","url":"https:\/\/www.juddbuilders.com\/juddbuildersblog\/wp-json\/wp\/v2\/tags\/837\/","name":"Townhouse | Judd Builders","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.juddbuilders.com\/juddbuildersblog\/#website"},"breadcrumb":{"@id":"https:\/\/www.juddbuilders.com\/juddbuildersblog\/wp-json\/wp\/v2\/tags\/837\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/www.juddbuilders.com\/juddbuildersblog\/#organization","name":"Judd Builders","url":"https:\/\/www.juddbuilders.com\/juddbuildersblog\/"},{"@type":"WebSite","@id":"https:\/\/www.juddbuilders.com\/juddbuildersblog\/#website","url":"https:\/\/www.juddbuilders.com\/juddbuildersblog\/","name":"Judd Builders","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.juddbuilders.com\/juddbuildersblog\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.juddbuilders.com\/juddbuildersblog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tTownhouse\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.juddbuilders.com\/juddbuildersblog"},{"label":"Townhouse","link":"https:\/\/www.juddbuilders.com\/juddbuildersblog\/tag\/townhouse\/"}],"_links":{"self":[{"href":"https:\/\/www.juddbuilders.com\/juddbuildersblog\/wp-json\/wp\/v2\/tags\/837"}],"collection":[{"href":"https:\/\/www.juddbuilders.com\/juddbuildersblog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.juddbuilders.com\/juddbuildersblog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.juddbuilders.com\/juddbuildersblog\/wp-json\/wp\/v2\/posts?tags=837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}