{"id":182,"count":2,"description":"","link":"https:\/\/www.juddbuilders.com\/juddbuildersblog\/tag\/townhome-living\/","name":"Townhome Living","slug":"townhome-living","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.juddbuilders.com\/juddbuildersblog\/tag\/townhome-living\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.juddbuilders.com\\\/juddbuildersblog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/182\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.juddbuilders.com\\\/juddbuildersblog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.juddbuilders.com\\\/juddbuildersblog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.juddbuilders.com\\\/juddbuildersblog\\\/tag\\\/townhome-living\\\/#listItem\",\"name\":\"Townhome Living\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.juddbuilders.com\\\/juddbuildersblog\\\/tag\\\/townhome-living\\\/#listItem\",\"position\":2,\"name\":\"Townhome Living\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.juddbuilders.com\\\/juddbuildersblog#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.juddbuilders.com\\\/juddbuildersblog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/182\\\/#collectionpage\",\"url\":\"https:\\\/\\\/www.juddbuilders.com\\\/juddbuildersblog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/182\\\/\",\"name\":\"Townhome Living | Judd Builders\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.juddbuilders.com\\\/juddbuildersblog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.juddbuilders.com\\\/juddbuildersblog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/182\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.juddbuilders.com\\\/juddbuildersblog\\\/#organization\",\"name\":\"Judd Builders\",\"url\":\"https:\\\/\\\/www.juddbuilders.com\\\/juddbuildersblog\\\/\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.juddbuilders.com\\\/juddbuildersblog\\\/#website\",\"url\":\"https:\\\/\\\/www.juddbuilders.com\\\/juddbuildersblog\\\/\",\"name\":\"Judd Builders\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.juddbuilders.com\\\/juddbuildersblog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Townhome Living | Judd Builders","description":"","canonical_url":"https:\/\/www.juddbuilders.com\/juddbuildersblog\/tag\/townhome-living\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.juddbuilders.com\/juddbuildersblog\/wp-json\/wp\/v2\/tags\/182\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.juddbuilders.com\/juddbuildersblog#listItem","position":1,"name":"Home","item":"https:\/\/www.juddbuilders.com\/juddbuildersblog","nextItem":{"@type":"ListItem","@id":"https:\/\/www.juddbuilders.com\/juddbuildersblog\/tag\/townhome-living\/#listItem","name":"Townhome Living"}},{"@type":"ListItem","@id":"https:\/\/www.juddbuilders.com\/juddbuildersblog\/tag\/townhome-living\/#listItem","position":2,"name":"Townhome Living","previousItem":{"@type":"ListItem","@id":"https:\/\/www.juddbuilders.com\/juddbuildersblog#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/www.juddbuilders.com\/juddbuildersblog\/wp-json\/wp\/v2\/tags\/182\/#collectionpage","url":"https:\/\/www.juddbuilders.com\/juddbuildersblog\/wp-json\/wp\/v2\/tags\/182\/","name":"Townhome Living | Judd Builders","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.juddbuilders.com\/juddbuildersblog\/#website"},"breadcrumb":{"@id":"https:\/\/www.juddbuilders.com\/juddbuildersblog\/wp-json\/wp\/v2\/tags\/182\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/www.juddbuilders.com\/juddbuildersblog\/#organization","name":"Judd Builders","url":"https:\/\/www.juddbuilders.com\/juddbuildersblog\/"},{"@type":"WebSite","@id":"https:\/\/www.juddbuilders.com\/juddbuildersblog\/#website","url":"https:\/\/www.juddbuilders.com\/juddbuildersblog\/","name":"Judd Builders","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.juddbuilders.com\/juddbuildersblog\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.juddbuilders.com\/juddbuildersblog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tTownhome Living\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.juddbuilders.com\/juddbuildersblog"},{"label":"Townhome Living","link":"https:\/\/www.juddbuilders.com\/juddbuildersblog\/tag\/townhome-living\/"}],"_links":{"self":[{"href":"https:\/\/www.juddbuilders.com\/juddbuildersblog\/wp-json\/wp\/v2\/tags\/182"}],"collection":[{"href":"https:\/\/www.juddbuilders.com\/juddbuildersblog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.juddbuilders.com\/juddbuildersblog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.juddbuilders.com\/juddbuildersblog\/wp-json\/wp\/v2\/posts?tags=182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}